{"id":13122,"date":"2025-09-22T19:28:52","date_gmt":"2025-09-22T17:28:52","guid":{"rendered":"http:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428.jpg"},"modified":"2025-09-22T19:28:52","modified_gmt":"2025-09-22T17:28:52","slug":"dsc03428","status":"inherit","type":"attachment","link":"https:\/\/www.ffhennersdorf.at\/WordPress\/2025\/09\/20\/wohnhausbrandendetglimpflich\/dsc03428\/#main","title":{"rendered":"DSC03428"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-300x200.jpg 300w, https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-1024x683.jpg 1024w, https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-768x512.jpg 768w, https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-1536x1024.jpg 1536w, https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2025\/09\/DSC03428-scaled.jpg","filesize":393634,"sizes":{"medium":{"file":"DSC03428-300x200.jpg","width":300,"height":200,"filesize":47118,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-300x200.jpg"},"large":{"file":"DSC03428-1024x683.jpg","width":1024,"height":683,"filesize":123313,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-1024x683.jpg"},"thumbnail":{"file":"DSC03428-150x150.jpg","width":150,"height":150,"filesize":39853,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-150x150.jpg"},"medium_large":{"file":"DSC03428-768x512.jpg","width":768,"height":512,"filesize":90815,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-768x512.jpg"},"1536x1536":{"file":"DSC03428-1536x1024.jpg","width":1536,"height":1024,"filesize":198248,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-1536x1024.jpg"},"2048x2048":{"file":"DSC03428-2048x1365.jpg","width":2048,"height":1365,"filesize":288124,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-2048x1365.jpg"},"catchresponsive-slider":{"file":"DSC03428-1200x514.jpg","width":1200,"height":514,"filesize":113704,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-1200x514.jpg"},"catchresponsive-featured-content":{"file":"DSC03428-350x197.jpg","width":350,"height":197,"filesize":48773,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-350x197.jpg"},"catchresponsive-hero":{"file":"DSC03428-528x297.jpg","width":528,"height":297,"filesize":62480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-528x297.jpg"},"catchresponsive-featured":{"file":"DSC03428-860x484.jpg","width":860,"height":484,"filesize":94171,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-860x484.jpg"},"catchresponsive-square":{"file":"DSC03428-200x200.jpg","width":200,"height":200,"filesize":43635,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-200x200.jpg"},"catchresponsive-sm-square":{"file":"DSC03428-100x100.jpg","width":100,"height":100,"filesize":36877,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-100x100.jpg"},"catchresponsive-stats":{"file":"DSC03428-40x40.jpg","width":40,"height":40,"filesize":33934,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-40x40.jpg"},"full":{"file":"DSC03428-scaled.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-scaled.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"ILCE-7M3","caption":"","created_timestamp":"1758359100","copyright":"","focal_length":"28","iso":"160","shutter_speed":"0.016666666666667","title":"","orientation":"0","keywords":[]},"original_image":"DSC03428.jpg"},"post":13115,"source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2025\/09\/DSC03428-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/media\/13122"}],"collection":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/comments?post=13122"}]}}