{"id":295,"date":"2016-05-24T21:52:44","date_gmt":"2016-05-24T19:52:44","guid":{"rendered":"http:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6.jpg"},"modified":"2016-05-24T21:52:44","modified_gmt":"2016-05-24T19:52:44","slug":"bewerbe-6","status":"inherit","type":"attachment","link":"https:\/\/www.ffhennersdorf.at\/WordPress\/aktivitaeten\/bewerbe\/bewerbe-6\/#main","title":{"rendered":"Bewerbe (6)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6-300x200.jpg 300w, https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":500,"height":333,"file":"2016\/04\/Bewerbe-6.jpg","sizes":{"thumbnail":{"file":"Bewerbe-6-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6-150x150.jpg"},"medium":{"file":"Bewerbe-6-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6-300x200.jpg"},"catchresponsive-featured-content":{"file":"Bewerbe-6-350x197.jpg","width":350,"height":197,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6-350x197.jpg"},"catchresponsive-square":{"file":"Bewerbe-6-200x200.jpg","width":200,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6-200x200.jpg"},"full":{"file":"Bewerbe-6.jpg","width":500,"height":333,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6.jpg"}},"image_meta":{"aperture":"4.5","credit":"","camera":"Canon EOS 650D","caption":"","created_timestamp":"1434818996","copyright":"","focal_length":"35","iso":"100","shutter_speed":"0.004","title":"","orientation":"1","keywords":[]}},"post":14,"source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Bewerbe-6.jpg","_links":{"self":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/media\/295"}],"collection":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/comments?post=295"}]}}