{"id":536,"date":"2016-05-28T15:30:37","date_gmt":"2016-05-28T13:30:37","guid":{"rendered":"http:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3.jpg"},"modified":"2016-05-28T15:30:37","modified_gmt":"2016-05-28T13:30:37","slug":"feuerwehrfeste-3","status":"inherit","type":"attachment","link":"https:\/\/www.ffhennersdorf.at\/WordPress\/aktivitaeten\/feuerwehrfest\/feuerwehrfeste-3\/#main","title":{"rendered":"Feuerwehrfeste (3)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3-300x225.jpg 300w, https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":500,"height":375,"file":"2016\/04\/Feuerwehrfeste-3.jpg","sizes":{"thumbnail":{"file":"Feuerwehrfeste-3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3-150x150.jpg"},"medium":{"file":"Feuerwehrfeste-3-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3-300x225.jpg"},"catchresponsive-featured-content":{"file":"Feuerwehrfeste-3-350x197.jpg","width":350,"height":197,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3-350x197.jpg"},"catchresponsive-square":{"file":"Feuerwehrfeste-3-200x200.jpg","width":200,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3-200x200.jpg"},"full":{"file":"Feuerwehrfeste-3.jpg","width":500,"height":375,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3.jpg"}},"image_meta":{"aperture":"3.2","credit":"","camera":"COOLPIX P7100","caption":"","created_timestamp":"1338664388","copyright":"","focal_length":"8.1","iso":"140","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]}},"post":16,"source_url":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-content\/uploads\/2016\/04\/Feuerwehrfeste-3.jpg","_links":{"self":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/media\/536"}],"collection":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ffhennersdorf.at\/WordPress\/wp-json\/wp\/v2\/comments?post=536"}]}}